{"id":553,"count":3,"description":"","link":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/","name":"Layers","slug":"layers-en","taxonomy":"product_cat","parent":540,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Layers Archieven - IbbelDibbel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Layers Archieven - IbbelDibbel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/\" \/>\n<meta property=\"og:site_name\" content=\"IbbelDibbel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/\",\"url\":\"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/\",\"name\":\"Layers Archieven - IbbelDibbel\",\"isPartOf\":{\"@id\":\"https:\/\/www.ibbeldibbel.nl\/nl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ibbeldibbel.nl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collections\",\"item\":\"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Layers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ibbeldibbel.nl\/nl\/#website\",\"url\":\"https:\/\/www.ibbeldibbel.nl\/nl\/\",\"name\":\"IbbelDibbel\",\"description\":\"Dots, dots en dots\",\"publisher\":{\"@id\":\"https:\/\/www.ibbeldibbel.nl\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ibbeldibbel.nl\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ibbeldibbel.nl\/nl\/#organization\",\"name\":\"Ibbel Dibbel\",\"url\":\"https:\/\/www.ibbeldibbel.nl\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ibbeldibbel.nl\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ibbeldibbel.nl\/wp-content\/uploads\/2015\/01\/logo-ID-webite.png\",\"contentUrl\":\"https:\/\/www.ibbeldibbel.nl\/wp-content\/uploads\/2015\/01\/logo-ID-webite.png\",\"width\":340,\"height\":156,\"caption\":\"Ibbel Dibbel\"},\"image\":{\"@id\":\"https:\/\/www.ibbeldibbel.nl\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ibbeldibbel\/\",\"https:\/\/x.com\/IbbelDibbel\",\"https:\/\/www.instagram.com\/ibbeldibbeldots\/\",\"https:\/\/www.linkedin.com\/in\/yolandabros\/\",\"https:\/\/nl.pinterest.com\/ibbeldibbeldotpainting\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Layers Archieven - IbbelDibbel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/","og_locale":"en_US","og_type":"article","og_title":"Layers Archieven - IbbelDibbel","og_url":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/","og_site_name":"IbbelDibbel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/","url":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/","name":"Layers Archieven - IbbelDibbel","isPartOf":{"@id":"https:\/\/www.ibbeldibbel.nl\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/layers-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ibbeldibbel.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Collections","item":"https:\/\/www.ibbeldibbel.nl\/en\/product-categorie\/collections\/"},{"@type":"ListItem","position":3,"name":"Layers"}]},{"@type":"WebSite","@id":"https:\/\/www.ibbeldibbel.nl\/nl\/#website","url":"https:\/\/www.ibbeldibbel.nl\/nl\/","name":"IbbelDibbel","description":"Dots, dots en dots","publisher":{"@id":"https:\/\/www.ibbeldibbel.nl\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ibbeldibbel.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ibbeldibbel.nl\/nl\/#organization","name":"Ibbel Dibbel","url":"https:\/\/www.ibbeldibbel.nl\/nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ibbeldibbel.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.ibbeldibbel.nl\/wp-content\/uploads\/2015\/01\/logo-ID-webite.png","contentUrl":"https:\/\/www.ibbeldibbel.nl\/wp-content\/uploads\/2015\/01\/logo-ID-webite.png","width":340,"height":156,"caption":"Ibbel Dibbel"},"image":{"@id":"https:\/\/www.ibbeldibbel.nl\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ibbeldibbel\/","https:\/\/x.com\/IbbelDibbel","https:\/\/www.instagram.com\/ibbeldibbeldots\/","https:\/\/www.linkedin.com\/in\/yolandabros\/","https:\/\/nl.pinterest.com\/ibbeldibbeldotpainting\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.ibbeldibbel.nl\/en\/wp-json\/wp\/v2\/product_cat\/553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibbeldibbel.nl\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.ibbeldibbel.nl\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.ibbeldibbel.nl\/en\/wp-json\/wp\/v2\/product_cat\/540"}],"wp:post_type":[{"href":"https:\/\/www.ibbeldibbel.nl\/en\/wp-json\/wp\/v2\/product?product_cat=553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}